{"id":1479,"count":2,"description":"Una mezcla de eficiencia de una bicicleta de carretera, comodidad de una MTB, estilo en una bicicleta urbana. Esta bicicleta para viajes diarios cuenta con un cuadro AL6 resistente, liviano y partes de la mejor bicicleta para viajes diarios. La Polygon Path es la bicicleta perfecta para paseos sociales con amigos o para llegar a tiempo esquivando el tr\u00e1fico de la ciudad.","link":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/path-es\/","name":"PATH","slug":"path-es","taxonomy":"product_cat","parent":1117,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/wp-json\/wp\/v2\/product_cat\/1479"}],"collection":[{"href":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/wp-json\/wp\/v2\/product_cat\/1117"}],"wp:post_type":[{"href":"https:\/\/polygon-wp-2021.tongkolspace.com\/es\/wp-json\/wp\/v2\/product?product_cat=1479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}